{"id":51526,"date":"2023-02-07T16:54:50","date_gmt":"2023-02-07T09:54:50","guid":{"rendered":"https:\/\/shopee.co.th\/blog\/?p=51526"},"modified":"2023-05-29T16:47:35","modified_gmt":"2023-05-29T09:47:35","slug":"romantic-disney-plus-movies","status":"publish","type":"post","link":"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/","title":{"rendered":"7 \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e2b\u0e27\u0e32\u0e19\u0e0b\u0e36\u0e49\u0e07 \u0e15\u0e23\u0e36\u0e07\u0e43\u0e08 \u0e23\u0e49\u0e2d\u0e07\u0e44\u0e2b\u0e49\u0e08\u0e19\u0e15\u0e31\u0e1a\u0e1e\u0e31\u0e07"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e27\u0e31\u0e19\u0e27\u0e32\u0e40\u0e25\u0e19\u0e44\u0e17\u0e19\u0e4c\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e39\u0e48\u0e04\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e09\u0e25\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e15\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e14\u0e35 \u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e0a\u0e27\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e48\u0e07\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e14\u0e39\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e2b\u0e32\u0e01\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e44\u0e1b\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e43\u0e19\u0e42\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e09\u0e25\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e33\u0e04\u0e37\u0e19\u0e2a\u0e38\u0e14\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e23\u0e31\u0e01\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19 \u0e25\u0e2d\u0e07\u0e0a\u0e27\u0e19\u0e01\u0e31\u0e19\u0e21\u0e32\u0e19\u0e2d\u0e19\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e2b\u0e27\u0e32\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e21\u0e35 \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e39\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e2b\u0e27\u0e32\u0e19\u0e0b\u0e36\u0e49\u0e07 \u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e2d\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a9805a6e278a\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a9805a6e278a\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#1_Beauty_and_the_Beast_2017\" >1. Beauty and the Beast (2017)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD\" >\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#2_Aladdin_2019\" >2. Aladdin (2019)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-2\" >\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#3_Clouds_2020\" >3. Clouds (2020)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-3\" >\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#4_Stargirl_2020\" >4. Stargirl (2020)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-4\" >\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#5_Cinderella_2015\" >5. Cinderella (2015)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-5\" >\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#6_The_Last_Song_2010\" >6. The Last Song (2010)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-6\" >\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#7_While_You_Were_Sleeping_1995\" >7. While You Were Sleeping (1995)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/shopee.co.th\/blog\/romantic-disney-plus-movies\/#%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-7\" >\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"has-text-align-center wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Beauty_and_the_Beast_2017\"><\/span><strong>1. Beauty and the Beast (2017)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Beauty and the Beast \u2013 US Official Final Trailer\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/e3Nl_TCQXuw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD\"><\/span><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e31\u0e19\u0e19\u0e48\u0e32\u0e2d\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e1a\u0e25\u0e25\u0e4c \u0e2b\u0e0d\u0e34\u0e07\u0e2a\u0e32\u0e27\u0e1c\u0e39\u0e49\u0e2a\u0e14\u0e43\u0e2a \u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e2d\u0e34\u0e2a\u0e23\u0e30 \u0e40\u0e18\u0e2d\u0e16\u0e39\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e23\u0e49\u0e32\u0e22\u0e08\u0e31\u0e1a\u0e02\u0e31\u0e07\u0e44\u0e27\u0e49\u0e43\u0e19\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e18\u0e2d\u0e08\u0e30\u0e01\u0e25\u0e31\u0e27 \u0e41\u0e15\u0e48\u0e40\u0e18\u0e2d\u0e01\u0e47\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e1c\u0e39\u0e01\u0e21\u0e34\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e21\u0e23\u0e39\u0e1b\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e40\u0e01\u0e25\u0e35\u0e22\u0e14\u0e19\u0e48\u0e32\u0e01\u0e25\u0e31\u0e27\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e08\u0e34\u0e15\u0e43\u0e08\u0e2d\u0e31\u0e19\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e0a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e23\u0e49\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2a\u0e39\u0e23\u0e19\u0e31\u0e49\u0e19\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e40\u0e08\u0e49\u0e32\u0e0a\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e22\u0e48\u0e2d\u0e2b\u0e22\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e2a\u0e32\u0e1b \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e1c\u0e39\u0e01\u0e1e\u0e31\u0e19 \u0e08\u0e30\u0e01\u0e48\u0e2d\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e25\u0e32\u0e14\u0e0a\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49 !<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17: \u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\/ \u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35<\/li><li>\u0e40\u0e23\u0e17: PG<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27: 2 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 9 \u0e19\u0e32\u0e17\u0e35<\/li><li>\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e33: \u0e40\u0e1a\u0e25\u0e25\u0e4c \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e2d\u0e47\u0e21\u0e21\u0e48\u0e32 \u0e27\u0e31\u0e15\u0e2a\u0e31\u0e19\/ \u0e2d\u0e14\u0e31\u0e21 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e41\u0e14\u0e19 \u0e2a\u0e15\u0e35\u0e40\u0e27\u0e19\u0e2a\u0e4c<\/li><li>\u0e40\u0e23\u0e17\u0e15\u0e34\u0e49\u0e07 IMDB: 7.1\/10<\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Aladdin_2019\"><\/span><strong>2. Aladdin (2019)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Disney&#039;s Aladdin Official Trailer - In Theaters May 24!\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/foyufD52aog?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-2\"><\/span><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e09\u0e1a\u0e31\u0e1a live-action \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07 \u0e2d\u0e30\u0e25\u0e32\u0e14\u0e34\u0e19 \u0e40\u0e14\u0e47\u0e01\u0e01\u0e33\u0e1e\u0e23\u0e49\u0e32\u0e02\u0e49\u0e32\u0e07\u0e16\u0e19\u0e19\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e31\u0e01\u0e23\u0e32\u0e1a\u0e32\u0e2b\u0e4c\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e1a\u0e39 \u0e25\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e0d\u0e34\u0e07\u0e08\u0e31\u0e2a\u0e21\u0e34\u0e19\u0e1c\u0e39\u0e49\u0e07\u0e14\u0e07\u0e32\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e2d\u0e1a\u0e2b\u0e19\u0e35\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e31\u0e07 \u0e40\u0e18\u0e2d\u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e37\u0e1a\u0e15\u0e48\u0e2d\u0e08\u0e32\u0e01\u0e1e\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2a\u0e38\u0e25\u0e15\u0e48\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e16\u0e39\u0e01\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e2b\u0e21\u0e31\u0e49\u0e19\u0e04\u0e39\u0e48\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e41\u0e17\u0e19 \u0e08\u0e32\u0e1f\u0e32\u0e23\u0e4c \u0e23\u0e32\u0e0a\u0e21\u0e19\u0e15\u0e23\u0e35\u0e1c\u0e39\u0e49\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e42\u0e04\u0e48\u0e19\u0e25\u0e49\u0e21\u0e2a\u0e38\u0e25\u0e15\u0e48\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e15\u0e30\u0e40\u0e01\u0e35\u0e22\u0e07\u0e27\u0e34\u0e40\u0e28\u0e29 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e08\u0e0d\u0e20\u0e31\u0e22\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e0a\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e32\u0e40\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19\u0e08\u0e31\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 \u0e41\u0e19\u0e30\u0e19\u0e4d\u0e32 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17: \u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\/ \u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35\/ \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27<\/li><li>\u0e40\u0e23\u0e17: 13+<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27: 2 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 10 \u0e19\u0e32\u0e17\u0e35<\/li><li>\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e33: \u0e08\u0e34\u0e19\u0e19\u0e35\u0e48 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e27\u0e34\u0e25 \u0e2a\u0e21\u0e34\u0e18\/ \u0e2d\u0e30\u0e25\u0e32\u0e14\u0e34\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e21\u0e19\u0e32 \u0e41\u0e21\u0e2a\u0e0b\u0e39\u0e14\/ \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e0d\u0e34\u0e07\u0e08\u0e31\u0e2a\u0e21\u0e34\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e19\u0e32\u0e42\u0e2d\u0e21\u0e34 \u0e2a\u0e01\u0e47\u0e2d\u0e15\u0e15\u0e4c<\/li><li>\u0e40\u0e23\u0e17\u0e15\u0e34\u0e49\u0e07 IMDB: 6.9\/10<\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Clouds_2020\"><\/span><strong>3. Clouds (2020)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Clouds l Official Trailer | Disney+\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/OWEgUhWU4g4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-3\"><\/span><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e08\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 \u0e41\u0e19\u0e30\u0e19\u0e4d\u0e32 \u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e02\u0e2d\u0e07 \u0e41\u0e0b\u0e04 \u0e42\u0e0b\u0e1a\u0e35\u0e04 \u0e19\u0e31\u0e01\u0e14\u0e19\u0e15\u0e23\u0e35\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e2a\u0e39\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e08\u0e30\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e35\u0e01\u0e44\u0e21\u0e48\u0e19\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e02\u0e32\u0e01\u0e47\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e44\u0e25\u0e48\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1d\u0e31\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e2d\u0e31\u0e25\u0e1a\u0e31\u0e49\u0e21\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e08\u0e32\u0e01\u0e41\u0e0b\u0e21\u0e21\u0e35\u0e48 \u0e1a\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e2a\u0e19\u0e34\u0e17\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e43\u0e04\u0e23\u0e0a\u0e2d\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e2a\u0e38\u0e14\u0e0b\u0e36\u0e49\u0e07 \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e1a\u0e1e\u0e31\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 !<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17: \u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\/ \u0e14\u0e23\u0e32\u0e21\u0e48\u0e32\/ \u0e0a\u0e35\u0e27\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34<\/li><li>\u0e40\u0e23\u0e17: 15+<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27: 2 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 1 \u0e19\u0e32\u0e17\u0e35<\/li><li>\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e33: \u0e41\u0e0b\u0e04 \u0e42\u0e0b\u0e1a\u0e35\u0e04 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e1f\u0e34\u0e19 \u0e2d\u0e32\u0e23\u0e4c\u0e01\u0e31\u0e2a\/ \u0e41\u0e0b\u0e21\u0e21\u0e35\u0e48 \u0e1a\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e0b\u0e32\u0e1a\u0e23\u0e35\u0e19\u0e32 \u0e04\u0e32\u0e23\u0e4c\u0e40\u0e1e\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\/ \u0e25\u0e2d\u0e23\u0e48\u0e32 \u0e42\u0e0b\u0e1a\u0e35\u0e04 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e19\u0e35\u0e1f \u0e41\u0e04\u0e21\u0e1b\u0e4c\u0e40\u0e1a\u0e25\/ \u0e40\u0e2d\u0e21\u0e35 \u0e2d\u0e14\u0e31\u0e21\u0e25\u0e4c \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e21\u0e14\u0e34\u0e2a\u0e31\u0e19 \u0e2d\u0e34\u0e0b\u0e41\u0e21\u0e19<\/li><li>\u0e40\u0e23\u0e17\u0e15\u0e34\u0e49\u0e07 IMDB: 7.5\/10<\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Stargirl_2020\"><\/span><strong>4. Stargirl (2020)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Stargirl | Official Trailer | Disney+\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/fE-e7v4bvxw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-4\"><\/span><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2d\u0e35\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e25\u0e35\u0e42\u0e2d \u0e1a\u0e2d\u0e23\u0e4c\u0e25\u0e47\u0e2d\u0e04 \u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e21\u0e01\u0e32 \u0e23\u0e31\u0e10\u0e41\u0e2d\u0e23\u0e34\u0e42\u0e0b\u0e19\u0e32 \u0e17\u0e35\u0e48\u0e42\u0e28\u0e01\u0e40\u0e28\u0e23\u0e49\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e1e\u0e48\u0e2d \u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21 \u0e25\u0e35\u0e42\u0e2d\u0e40\u0e25\u0e48\u0e19\u0e17\u0e23\u0e31\u0e21\u0e40\u0e1b\u0e47\u0e15\u0e43\u0e19\u0e27\u0e07\u0e42\u0e22\u0e18\u0e27\u0e32\u0e17\u0e34\u0e15 \u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e0b\u0e39\u0e0b\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e25 \u0e2a\u0e32\u0e27\u0e19\u0e49\u0e2d\u0e22\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e2d\u0e34\u0e2a\u0e23\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e40\u0e18\u0e2d\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e14\u0e36\u0e07\u0e40\u0e02\u0e32\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e41\u0e2a\u0e19\u0e40\u0e28\u0e23\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e0a\u0e2d\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01 \u0e46 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e25\u0e32\u0e14\u0e0a\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17: \u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\/ \u0e14\u0e23\u0e32\u0e21\u0e48\u0e32<\/li><li>\u0e40\u0e23\u0e17: PG<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27: 1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 43 \u0e19\u0e32\u0e17\u0e35<\/li><li>\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e33: \u0e0b\u0e39\u0e0b\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e01\u0e23\u0e0b \u0e41\u0e27\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e27\u0e32\u0e25\/ \u0e25\u0e35\u0e42\u0e2d \u0e1a\u0e2d\u0e23\u0e4c\u0e25\u0e47\u0e2d\u0e04 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e01\u0e23\u0e41\u0e2e\u0e21 \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e41\u0e0a\u0e23\u0e4c<\/li><li>\u0e40\u0e23\u0e17\u0e15\u0e34\u0e49\u0e07 IMDB: 6.2\/10<\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Cinderella_2015\"><\/span><strong>5. Cinderella (2015)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Disney&#039;s Cinderella Official US Trailer\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/20DF6U1HcGQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-5\"><\/span><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e08\u0e32\u0e01\u0e40\u0e17\u0e1e\u0e19\u0e34\u0e22\u0e32\u0e22\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01 \u0e2a\u0e39\u0e48\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 \u0e41\u0e19\u0e30\u0e19\u0e4d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e0b\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e40\u0e23\u0e25\u0e25\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e30\u0e17\u0e31\u0e19\u0e2b\u0e31\u0e19 \u0e0b\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e40\u0e23\u0e25\u0e25\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e25\u0e25\u0e48\u0e32\u0e43\u0e19\u0e27\u0e31\u0e22\u0e40\u0e22\u0e32\u0e27\u0e4c\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e27\u0e32\u0e21\u0e14\u0e39\u0e41\u0e25\u0e02\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e43\u0e08\u0e23\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e25\u0e39\u0e01\u0e2a\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d \u0e41\u0e21\u0e49\u0e08\u0e30\u0e16\u0e39\u0e01\u0e41\u0e21\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e19\u0e49\u0e2d\u0e07\u0e2a\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e02\u0e48\u0e21\u0e40\u0e2b\u0e07 \u0e40\u0e2d\u0e25\u0e25\u0e48\u0e32\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e32\u0e40\u0e23\u0e34\u0e07\u0e01\u0e47\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e17\u0e35\u0e48\u0e08\u0e30\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e0a\u0e30\u0e15\u0e32\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e25\u0e49\u0e27\u0e42\u0e0a\u0e04\u0e0a\u0e30\u0e15\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e25\u0e25\u0e48\u0e32\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e41\u0e1b\u0e25\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e1b\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e07\u0e1f\u0e49\u0e32\u0e41\u0e21\u0e48\u0e17\u0e39\u0e19\u0e2b\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e01\u0e49\u0e27 ! \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e0a\u0e2d\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e48\u0e19\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e0b\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e40\u0e23\u0e25\u0e25\u0e48\u0e32\u0e01\u0e47\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e14\u0e39<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17: \u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\/ \u0e14\u0e23\u0e32\u0e21\u0e48\u0e32<\/li><li>\u0e40\u0e23\u0e17: PG<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27: 1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 41 \u0e19\u0e32\u0e17\u0e35<\/li><li>\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e33: \u0e0b\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e40\u0e23\u0e25\u0e25\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e25\u0e34\u0e25\u0e35\u0e48 \u0e40\u0e08\u0e21\u0e2a\u0e4c\/ \u0e40\u0e25\u0e14\u0e35\u0e49 \u0e40\u0e17\u0e23\u0e40\u0e21\u0e19 (\u0e41\u0e21\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07) \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e04\u0e15 \u0e41\u0e1a\u0e25\u0e19\u0e40\u0e0a\u0e15\u0e15\u0e4c\/ \u0e40\u0e08\u0e49\u0e32\u0e0a\u0e32\u0e22\u0e04\u0e34\u0e17 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e23\u0e34\u0e0a\u0e32\u0e23\u0e4c\u0e14 \u0e41\u0e21\u0e14\u0e40\u0e14\u0e19<\/li><li>\u0e40\u0e23\u0e17\u0e15\u0e34\u0e49\u0e07 IMDB: 6.9\/10<\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_The_Last_Song_2010\"><\/span><strong>6. The Last Song (2010)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"The Last Song | &quot;Trailer&quot; (Official)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/7v88MYrr9hE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-6\"><\/span><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">The Last Song \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e23\u0e2d\u0e19\u0e19\u0e35\u0e48\u0e41\u0e25\u0e30\u0e1e\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e2b\u0e48\u0e32\u0e07\u0e40\u0e2b\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e2a\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e2a\u0e32\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e18\u0e2d \u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e2a\u0e32\u0e27\u0e2b\u0e31\u0e27\u0e23\u0e31\u0e49\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e07\u0e48\u0e32\u0e22 \u0e40\u0e27\u0e42\u0e23\u0e19\u0e34\u0e01\u0e32 \u0e23\u0e2d\u0e19\u0e19\u0e35\u0e48 \u0e21\u0e34\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e47\u0e01\u0e27\u0e31\u0e22 17 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e2b\u0e31\u0e27\u0e23\u0e31\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e2b\u0e22\u0e48\u0e32\u0e23\u0e49\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e2b\u0e19\u0e35\u0e44\u0e1b\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e08\u0e35\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e21\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e18\u0e2d\u0e40\u0e04\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e14\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e35\u0e22\u0e42\u0e19\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e02\u0e2d\u0e07\u0e1e\u0e48\u0e2d \u0e41\u0e15\u0e48\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e18\u0e2d\u0e40\u0e25\u0e34\u0e01\u0e40\u0e25\u0e48\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e40\u0e25\u0e22\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e02\u0e32\u0e08\u0e32\u0e01\u0e44\u0e1b \u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e27\u0e31\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e07\u0e40\u0e18\u0e2d\u0e41\u0e25\u0e30\u0e19\u0e49\u0e2d\u0e07\u0e0a\u0e32\u0e22\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e24\u0e14\u0e39\u0e23\u0e49\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e48\u0e2d\u0e43\u0e19\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e08\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e48\u0e19\u0e08\u0e36\u0e07\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1e\u0e48\u0e2d\u0e25\u0e39\u0e01\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e41\u0e19\u0e27\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e08\u0e31\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e04\u0e27\u0e23\u0e04\u0e48\u0e32\u0e41\u0e01\u0e48\u0e01\u0e32\u0e23\u0e14\u0e39<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17: \u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\/ \u0e14\u0e23\u0e32\u0e21\u0e48\u0e32<\/li><li>\u0e40\u0e23\u0e17: 13+<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27: 1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 43 \u0e19\u0e32\u0e17\u0e35<\/li><li>\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e33: \u0e40\u0e27\u0e42\u0e23\u0e19\u0e34\u0e01\u0e32 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e44\u0e21\u0e25\u0e35\u0e22\u0e4c \u0e44\u0e0b\u0e23\u0e31\u0e2a\/ \u0e27\u0e34\u0e25 \u0e40\u0e1a\u0e25\u0e01\u0e25\u0e35 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e21 \u0e40\u0e2e\u0e21\u0e2a\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e18\/ \u0e2a\u0e15\u0e35\u0e1f \u0e21\u0e34\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e40\u0e01\u0e23\u0e47\u0e01 \u0e04\u0e34\u0e19\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c<\/li><li>\u0e40\u0e23\u0e17\u0e15\u0e34\u0e49\u0e07 IMDB: 6.0\/10<\/li><\/ul>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_While_You_Were_Sleeping_1995\"><\/span><strong>7. While You Were Sleeping (1995)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"While You Were Sleeping (1995) Trailer #1 | Movieclips Classic Trailers\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/nsJxyUvkB_E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%E0%B9%80%E0%B8%A3%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%87%E0%B8%A2%E0%B9%88%E0%B8%AD-7\"><\/span><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e19\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e1a \u0e25\u0e39\u0e0b\u0e35\u0e48 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e16\u0e44\u0e1f\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e14\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49\u0e15\u0e01\u0e2b\u0e25\u0e38\u0e21\u0e23\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e41\u0e1b\u0e25\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e18\u0e2d\u0e41\u0e2d\u0e1a\u0e21\u0e35\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e18\u0e2d\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e41\u0e25\u0e49\u0e27\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e18\u0e2d\u0e44\u0e14\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e40\u0e02\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e15\u0e01\u0e23\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e42\u0e04\u0e21\u0e48\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1c\u0e34\u0e14\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e25\u0e39\u0e0b\u0e35\u0e48\u0e41\u0e25\u0e30\u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e39\u0e48\u0e2b\u0e21\u0e31\u0e49\u0e19\u0e04\u0e39\u0e48\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e31\u0e19 ! \u0e41\u0e25\u0e30\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e01\u0e47\u0e01\u0e25\u0e31\u0e1a\u0e22\u0e38\u0e48\u0e07\u0e40\u0e2b\u0e22\u0e34\u0e07\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e2d\u0e35\u0e01 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e39\u0e0b\u0e35\u0e48\u0e14\u0e31\u0e19\u0e15\u0e01\u0e2b\u0e25\u0e38\u0e21\u0e23\u0e31\u0e01\u0e1e\u0e35\u0e48\u0e0a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e31\u0e01\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c ! \u0e21\u0e32\u0e40\u0e15\u0e34\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e27\u0e31\u0e19\u0e27\u0e32\u0e40\u0e25\u0e19\u0e44\u0e17\u0e19\u0e4c \u0e14\u0e49\u0e27\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e41\u0e19\u0e27\u0e23\u0e2d\u0e21\u0e04\u0e2d\u0e21\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e01\u0e31\u0e19 \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e19\u0e38\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17: \u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\/ \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e14\u0e35\u0e49<\/li><li>\u0e40\u0e23\u0e17: 13+<\/li><li>\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27: 1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 43 \u0e19\u0e32\u0e17\u0e35<\/li><li>\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e33: \u0e25\u0e39\u0e0b\u0e35\u0e48 \u0e40\u0e2d\u0e40\u0e25\u0e19\u0e2d\u0e23\u0e4c \u0e42\u0e21\u0e40\u0e14\u0e2d\u0e40\u0e23\u0e15\u0e0b\u0e4c \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e41\u0e0b\u0e19\u0e14\u0e23\u0e49\u0e32 \u0e1a\u0e39\u0e25\u0e25\u0e47\u0e2d\u0e04\/ \u0e41\u0e08\u0e47\u0e04 \u0e04\u0e31\u0e25\u0e25\u0e32\u0e41\u0e01\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e1a\u0e34\u0e25\u0e25\u0e4c \u0e1e\u0e39\u0e25\u0e41\u0e21\u0e19\/ \u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e04\u0e31\u0e25\u0e25\u0e32\u0e41\u0e01\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e31\u0e25\u0e25\u0e32\u0e40\u0e01\u0e2d\u0e23\u0e4c\/ \u0e2d\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e04\u0e31\u0e25\u0e25\u0e32\u0e41\u0e01\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e42\u0e14\u0e22 \u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1a\u0e2d\u0e22\u0e25\u0e4c<\/li><li>\u0e40\u0e23\u0e17\u0e15\u0e34\u0e49\u0e07 IMDB: 6.8\/10<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<br>\u0e41\u0e25\u0e30\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e14\u0e39 \u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e27\u0e32\u0e40\u0e25\u0e19\u0e44\u0e17\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e21\u0e32\u0e16\u0e36\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e41\u0e19\u0e27\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e23\u0e2a\u0e17\u0e38\u0e01\u0e2d\u0e32\u0e23\u0e21\u0e13\u0e4c \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e38\u0e02 \u0e40\u0e28\u0e23\u0e49\u0e32 \u0e40\u0e2b\u0e07\u0e32 \u0e0b\u0e36\u0e49\u0e07 \u0e15\u0e25\u0e01\u0e02\u0e1a\u0e02\u0e31\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e2b\u0e27\u0e32\u0e19\u0e09\u0e48\u0e33\u0e2b\u0e31\u0e27\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e0b\u0e32\u0e1a\u0e0b\u0e36\u0e49\u0e07\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e0a\u0e2d\u0e1a\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e31\u0e19\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19<a href=\"https:\/\/shopee.co.th\/blog\/best-romantic-thai-movies\/\"><strong><em>\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e44\u0e17\u0e22<\/em><\/strong><\/a><a href=\"https:\/\/shopee.co.th\/blog\/romantic-western-movies\/\"><strong><em>\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e1d\u0e23\u0e31\u0e48\u0e07<\/em><\/strong><\/a> \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e14\u0e35\u0e49 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2b\u0e32\u0e2d\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e43\u0e19 <strong><em>Shopee Blog<\/em><\/strong> \u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e16\u0e39\u0e01\u0e43\u0e08\u0e04\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e04\u0e23\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49<strong><em><a href=\"https:\/\/shopee.co.th\/%E0%B8%97%E0%B8%B5%E0%B8%A7%E0%B8%B5-cat.11044946.11045078\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e17\u0e35\u0e27\u0e35<\/a><\/em><\/strong>\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e46 \u0e21\u0e32\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e15\u0e32 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e49\u0e2d\u0e1b\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48<strong><em> Shopee <\/em><\/strong>\u0e40\u0e25\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e27\u0e32\u0e40\u0e25\u0e19\u0e44\u0e17\u0e19\u0e4c\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e39\u0e48\u0e04\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e09\u0e25\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e15\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e14\u0e35 \u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e0a\u0e27\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e48\u0e07\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e14\u0e39\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e2b\u0e32\u0e01\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e44\u0e1b\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e43\u0e19\u0e42\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e09\u0e25\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e33\u0e04\u0e37\u0e19\u0e2a\u0e38\u0e14\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e23\u0e31\u0e01\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19 \u0e25\u0e2d\u0e07\u0e0a\u0e27\u0e19\u0e01\u0e31\u0e19\u0e21\u0e32\u0e19\u0e2d\u0e19\u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e2b\u0e27\u0e32\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e21\u0e35 \u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e39\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e2b\u0e27\u0e32\u0e19\u0e0b\u0e36\u0e49\u0e07 \u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 1. Beauty and the Beast (2017) \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e48\u0e2d \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e25\u0e48\u0e32\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e31\u0e19\u0e19\u0e48\u0e32\u0e2d\u0e31\u0e28\u0e08\u0e23\u0e23\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e1a\u0e25\u0e25\u0e4c \u0e2b\u0e0d\u0e34\u0e07\u0e2a\u0e32\u0e27\u0e1c\u0e39\u0e49\u0e2a\u0e14\u0e43\u0e2a \u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e2d\u0e34\u0e2a\u0e23\u0e30 \u0e40\u0e18\u0e2d\u0e16\u0e39\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e23\u0e49\u0e32\u0e22\u0e08\u0e31\u0e1a\u0e02\u0e31\u0e07\u0e44\u0e27\u0e49\u0e43\u0e19\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e18\u0e2d\u0e08\u0e30\u0e01\u0e25\u0e31\u0e27 \u0e41\u0e15\u0e48\u0e40\u0e18\u0e2d\u0e01\u0e47\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e1c\u0e39\u0e01\u0e21\u0e34\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e21\u0e23\u0e39\u0e1b\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e40\u0e01\u0e25\u0e35\u0e22\u0e14\u0e19\u0e48\u0e32\u0e01\u0e25\u0e31\u0e27\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e08\u0e34\u0e15\u0e43\u0e08\u0e2d\u0e31\u0e19\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e0a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e23\u0e49\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2a\u0e39\u0e23\u0e19\u0e31\u0e49\u0e19\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e40\u0e08\u0e49\u0e32\u0e0a\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e22\u0e48\u0e2d\u0e2b\u0e22\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e33\u0e2a\u0e32\u0e1b \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e1c\u0e39\u0e01\u0e1e\u0e31\u0e19 \u0e08\u0e30\u0e01\u0e48\u0e2d\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e23\u0e31\u0e01\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e25\u0e32\u0e14\u0e0a\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e42\u0e23\u0e41\u0e21\u0e19\u0e15\u0e34\u0e01 Disney Plus [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":100354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","post_reading_time_wpm":"300","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo":"","sponsored_post_desc":""},"jnews_primary_category":{"id":""},"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[{"good_text":""}],"bad":[{"bad_text":""}],"score_override":"","override_value":"","rating":[{"rating_text":"","rating_number":"10"}],"price":[{"shop":"","price":"","link":"","icon":""}],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[975],"tags":[],"class_list":["post-51526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-movies-short-films"],"_links":{"self":[{"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/posts\/51526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/comments?post=51526"}],"version-history":[{"count":5,"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/posts\/51526\/revisions"}],"predecessor-version":[{"id":100356,"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/posts\/51526\/revisions\/100356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/media\/100354"}],"wp:attachment":[{"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/media?parent=51526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/categories?post=51526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shopee.co.th\/blog\/wp-json\/wp\/v2\/tags?post=51526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}